{"id":11164,"date":"2026-09-01T19:12:50","date_gmt":"2026-09-01T16:12:50","guid":{"rendered":"https:\/\/new.veele.eu\/product\/jaatisem-kommidega-jog-145g-tere\/"},"modified":"2026-09-01T19:12:51","modified_gmt":"2026-09-01T16:12:51","slug":"jaatisem-kommidega-jog-145g-tere","status":"publish","type":"product","link":"https:\/\/veele.eu\/en\/toode\/jaatisem-kommidega-jog-145g-tere\/","title":{"rendered":"J\u00c4\u00c4TISEM KOMMIDEGA JOG.145G (TERE)"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":13440,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[71,67],"product_tag":[],"class_list":["post-11164","product","type-product","status-publish","has-post-thumbnail","product_cat-jogurt-jogurtijook","product_cat-piimatooted","first","instock","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>J\u00c4\u00c4TISEM KOMMIDEGA JOG.145G (TERE)<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/veele.eu\/toode\/jaatisem-kommidega-jog-145g-tere\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"J\u00c4\u00c4TISEM KOMMIDEGA JOG.145G (TERE)\" \/>\n<meta property=\"og:url\" content=\"https:\/\/veele.eu\/toode\/jaatisem-kommidega-jog-145g-tere\/\" \/>\n<meta property=\"og:site_name\" content=\"VEELE Wholesale food market\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-01T16:12:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/veele.eu\/wp-content\/uploads\/2023\/10\/4740036013709_emma_jaatisemaitseline_jogurt_kommidega_block.png\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"0,68&euro;\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/veele.eu\\\/toode\\\/jaatisem-kommidega-jog-145g-tere\\\/\",\"url\":\"https:\\\/\\\/veele.eu\\\/toode\\\/jaatisem-kommidega-jog-145g-tere\\\/\",\"name\":\"J\u00c4\u00c4TISEM KOMMIDEGA JOG.145G (TERE)\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/veele.eu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/veele.eu\\\/toode\\\/jaatisem-kommidega-jog-145g-tere\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/veele.eu\\\/toode\\\/jaatisem-kommidega-jog-145g-tere\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/veele.eu\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/4740036013709_emma_jaatisemaitseline_jogurt_kommidega_block.png\",\"datePublished\":\"2026-09-01T16:12:50+00:00\",\"dateModified\":\"2026-09-01T16:12:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/veele.eu\\\/toode\\\/jaatisem-kommidega-jog-145g-tere\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/veele.eu\\\/toode\\\/jaatisem-kommidega-jog-145g-tere\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/veele.eu\\\/toode\\\/jaatisem-kommidega-jog-145g-tere\\\/#primaryimage\",\"url\":\"https:\\\/\\\/veele.eu\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/4740036013709_emma_jaatisemaitseline_jogurt_kommidega_block.png\",\"contentUrl\":\"https:\\\/\\\/veele.eu\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/4740036013709_emma_jaatisemaitseline_jogurt_kommidega_block.png\",\"width\":600,\"height\":600},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/veele.eu\\\/toode\\\/jaatisem-kommidega-jog-145g-tere\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/veele.eu\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Products\",\"item\":\"https:\\\/\\\/veele.eu\\\/en\\\/products\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"J\u00c4\u00c4TISEM KOMMIDEGA JOG.145G (TERE)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/veele.eu\\\/#website\",\"url\":\"https:\\\/\\\/veele.eu\\\/\",\"name\":\"VEELE Toidukaupade Hulgim\u00fc\u00fck\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/veele.eu\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/veele.eu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/veele.eu\\\/#organization\",\"name\":\"Veele O\u00dc\",\"url\":\"https:\\\/\\\/veele.eu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/veele.eu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/veele.eu\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/veele.jpg\",\"contentUrl\":\"https:\\\/\\\/veele.eu\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/veele.jpg\",\"width\":409,\"height\":373,\"caption\":\"Veele O\u00dc\"},\"image\":{\"@id\":\"https:\\\/\\\/veele.eu\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"0.68\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"4740036013709\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"J\u00c4\u00c4TISEM KOMMIDEGA JOG.145G (TERE)","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/veele.eu\/toode\/jaatisem-kommidega-jog-145g-tere\/","og_locale":"en_US","og_type":"article","og_title":"J\u00c4\u00c4TISEM KOMMIDEGA JOG.145G (TERE)","og_url":"https:\/\/veele.eu\/toode\/jaatisem-kommidega-jog-145g-tere\/","og_site_name":"VEELE Wholesale food market","article_modified_time":"2026-09-01T16:12:51+00:00","og_image":[{"width":600,"height":600,"url":"https:\/\/veele.eu\/wp-content\/uploads\/2023\/10\/4740036013709_emma_jaatisemaitseline_jogurt_kommidega_block.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"0,68&euro;","Availability":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/veele.eu\/toode\/jaatisem-kommidega-jog-145g-tere\/","url":"https:\/\/veele.eu\/toode\/jaatisem-kommidega-jog-145g-tere\/","name":"J\u00c4\u00c4TISEM KOMMIDEGA JOG.145G (TERE)","isPartOf":{"@id":"https:\/\/veele.eu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/veele.eu\/toode\/jaatisem-kommidega-jog-145g-tere\/#primaryimage"},"image":{"@id":"https:\/\/veele.eu\/toode\/jaatisem-kommidega-jog-145g-tere\/#primaryimage"},"thumbnailUrl":"https:\/\/veele.eu\/wp-content\/uploads\/2023\/10\/4740036013709_emma_jaatisemaitseline_jogurt_kommidega_block.png","datePublished":"2026-09-01T16:12:50+00:00","dateModified":"2026-09-01T16:12:51+00:00","breadcrumb":{"@id":"https:\/\/veele.eu\/toode\/jaatisem-kommidega-jog-145g-tere\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/veele.eu\/toode\/jaatisem-kommidega-jog-145g-tere\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/veele.eu\/toode\/jaatisem-kommidega-jog-145g-tere\/#primaryimage","url":"https:\/\/veele.eu\/wp-content\/uploads\/2023\/10\/4740036013709_emma_jaatisemaitseline_jogurt_kommidega_block.png","contentUrl":"https:\/\/veele.eu\/wp-content\/uploads\/2023\/10\/4740036013709_emma_jaatisemaitseline_jogurt_kommidega_block.png","width":600,"height":600},{"@type":"BreadcrumbList","@id":"https:\/\/veele.eu\/toode\/jaatisem-kommidega-jog-145g-tere\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/veele.eu\/en\/"},{"@type":"ListItem","position":2,"name":"Products","item":"https:\/\/veele.eu\/en\/products\/"},{"@type":"ListItem","position":3,"name":"J\u00c4\u00c4TISEM KOMMIDEGA JOG.145G (TERE)"}]},{"@type":"WebSite","@id":"https:\/\/veele.eu\/#website","url":"https:\/\/veele.eu\/","name":"VEELE Toidukaupade Hulgim\u00fc\u00fck","description":"","publisher":{"@id":"https:\/\/veele.eu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/veele.eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/veele.eu\/#organization","name":"Veele O\u00dc","url":"https:\/\/veele.eu\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/veele.eu\/#\/schema\/logo\/image\/","url":"https:\/\/veele.eu\/wp-content\/uploads\/2023\/07\/veele.jpg","contentUrl":"https:\/\/veele.eu\/wp-content\/uploads\/2023\/07\/veele.jpg","width":409,"height":373,"caption":"Veele O\u00dc"},"image":{"@id":"https:\/\/veele.eu\/#\/schema\/logo\/image\/"}}]},"product_price_amount":"0.68","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"4740036013709","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/veele.eu\/en\/wp-json\/wp\/v2\/product\/11164","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/veele.eu\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/veele.eu\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/veele.eu\/en\/wp-json\/wp\/v2\/media\/13440"}],"wp:attachment":[{"href":"https:\/\/veele.eu\/en\/wp-json\/wp\/v2\/media?parent=11164"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/veele.eu\/en\/wp-json\/wp\/v2\/product_brand?post=11164"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/veele.eu\/en\/wp-json\/wp\/v2\/product_cat?post=11164"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/veele.eu\/en\/wp-json\/wp\/v2\/product_tag?post=11164"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}