{"id":11790,"date":"2026-09-01T19:06:04","date_gmt":"2026-09-01T16:06:04","guid":{"rendered":"https:\/\/new.veele.eu\/toode\/merevaik-200gr-kukeseene-tere\/"},"modified":"2026-09-01T19:06:04","modified_gmt":"2026-09-01T16:06:04","slug":"merevaik-200gr-kukeseene-tere","status":"publish","type":"product","link":"https:\/\/veele.eu\/en\/toode\/merevaik-200gr-kukeseene-tere\/","title":{"rendered":"MEREVAIK 200GR  KUKESEENE (TERE)"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":20706,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[86,67],"product_tag":[],"class_list":["post-11790","product","type-product","status-publish","has-post-thumbnail","product_cat-juust","product_cat-piimatooted","first","instock","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>MEREVAIK 200GR KUKESEENE (TERE)<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/veele.eu\/toode\/merevaik-200gr-kukeseene-tere\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MEREVAIK 200GR KUKESEENE (TERE)\" \/>\n<meta property=\"og:url\" content=\"https:\/\/veele.eu\/toode\/merevaik-200gr-kukeseene-tere\/\" \/>\n<meta property=\"og:site_name\" content=\"VEELE Wholesale food market\" \/>\n<meta property=\"og:image\" content=\"https:\/\/veele.eu\/wp-content\/uploads\/2023\/10\/4740500000211.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"1,43&euro;\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/veele.eu\\\/toode\\\/merevaik-200gr-kukeseene-tere\\\/\",\"url\":\"https:\\\/\\\/veele.eu\\\/toode\\\/merevaik-200gr-kukeseene-tere\\\/\",\"name\":\"MEREVAIK 200GR KUKESEENE (TERE)\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/veele.eu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/veele.eu\\\/toode\\\/merevaik-200gr-kukeseene-tere\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/veele.eu\\\/toode\\\/merevaik-200gr-kukeseene-tere\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/veele.eu\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/4740500000211.webp\",\"datePublished\":\"2026-09-01T16:06:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/veele.eu\\\/toode\\\/merevaik-200gr-kukeseene-tere\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/veele.eu\\\/toode\\\/merevaik-200gr-kukeseene-tere\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/veele.eu\\\/toode\\\/merevaik-200gr-kukeseene-tere\\\/#primaryimage\",\"url\":\"https:\\\/\\\/veele.eu\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/4740500000211.webp\",\"contentUrl\":\"https:\\\/\\\/veele.eu\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/4740500000211.webp\",\"width\":800,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/veele.eu\\\/toode\\\/merevaik-200gr-kukeseene-tere\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/veele.eu\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Products\",\"item\":\"https:\\\/\\\/veele.eu\\\/en\\\/products\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"MEREVAIK 200GR KUKESEENE (TERE)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/veele.eu\\\/#website\",\"url\":\"https:\\\/\\\/veele.eu\\\/\",\"name\":\"VEELE Toidukaupade Hulgim\u00fc\u00fck\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/veele.eu\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/veele.eu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/veele.eu\\\/#organization\",\"name\":\"Veele O\u00dc\",\"url\":\"https:\\\/\\\/veele.eu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/veele.eu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/veele.eu\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/veele.jpg\",\"contentUrl\":\"https:\\\/\\\/veele.eu\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/veele.jpg\",\"width\":409,\"height\":373,\"caption\":\"Veele O\u00dc\"},\"image\":{\"@id\":\"https:\\\/\\\/veele.eu\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"1.43\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"4740500000211\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MEREVAIK 200GR KUKESEENE (TERE)","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/veele.eu\/toode\/merevaik-200gr-kukeseene-tere\/","og_locale":"en_US","og_type":"article","og_title":"MEREVAIK 200GR KUKESEENE (TERE)","og_url":"https:\/\/veele.eu\/toode\/merevaik-200gr-kukeseene-tere\/","og_site_name":"VEELE Wholesale food market","og_image":[{"width":800,"height":800,"url":"https:\/\/veele.eu\/wp-content\/uploads\/2023\/10\/4740500000211.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"1,43&euro;","Availability":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/veele.eu\/toode\/merevaik-200gr-kukeseene-tere\/","url":"https:\/\/veele.eu\/toode\/merevaik-200gr-kukeseene-tere\/","name":"MEREVAIK 200GR KUKESEENE (TERE)","isPartOf":{"@id":"https:\/\/veele.eu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/veele.eu\/toode\/merevaik-200gr-kukeseene-tere\/#primaryimage"},"image":{"@id":"https:\/\/veele.eu\/toode\/merevaik-200gr-kukeseene-tere\/#primaryimage"},"thumbnailUrl":"https:\/\/veele.eu\/wp-content\/uploads\/2023\/10\/4740500000211.webp","datePublished":"2026-09-01T16:06:04+00:00","breadcrumb":{"@id":"https:\/\/veele.eu\/toode\/merevaik-200gr-kukeseene-tere\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/veele.eu\/toode\/merevaik-200gr-kukeseene-tere\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/veele.eu\/toode\/merevaik-200gr-kukeseene-tere\/#primaryimage","url":"https:\/\/veele.eu\/wp-content\/uploads\/2023\/10\/4740500000211.webp","contentUrl":"https:\/\/veele.eu\/wp-content\/uploads\/2023\/10\/4740500000211.webp","width":800,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/veele.eu\/toode\/merevaik-200gr-kukeseene-tere\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/veele.eu\/en\/"},{"@type":"ListItem","position":2,"name":"Products","item":"https:\/\/veele.eu\/en\/products\/"},{"@type":"ListItem","position":3,"name":"MEREVAIK 200GR KUKESEENE (TERE)"}]},{"@type":"WebSite","@id":"https:\/\/veele.eu\/#website","url":"https:\/\/veele.eu\/","name":"VEELE Toidukaupade Hulgim\u00fc\u00fck","description":"","publisher":{"@id":"https:\/\/veele.eu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/veele.eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/veele.eu\/#organization","name":"Veele O\u00dc","url":"https:\/\/veele.eu\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/veele.eu\/#\/schema\/logo\/image\/","url":"https:\/\/veele.eu\/wp-content\/uploads\/2023\/07\/veele.jpg","contentUrl":"https:\/\/veele.eu\/wp-content\/uploads\/2023\/07\/veele.jpg","width":409,"height":373,"caption":"Veele O\u00dc"},"image":{"@id":"https:\/\/veele.eu\/#\/schema\/logo\/image\/"}}]},"product_price_amount":"1.43","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"4740500000211","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/veele.eu\/en\/wp-json\/wp\/v2\/product\/11790","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/veele.eu\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/veele.eu\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/veele.eu\/en\/wp-json\/wp\/v2\/media\/20706"}],"wp:attachment":[{"href":"https:\/\/veele.eu\/en\/wp-json\/wp\/v2\/media?parent=11790"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/veele.eu\/en\/wp-json\/wp\/v2\/product_brand?post=11790"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/veele.eu\/en\/wp-json\/wp\/v2\/product_cat?post=11790"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/veele.eu\/en\/wp-json\/wp\/v2\/product_tag?post=11790"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}