{"id":34864,"date":"2026-09-01T19:06:34","date_gmt":"2026-09-01T16:06:34","guid":{"rendered":"https:\/\/veele.eu\/toode\/broileri-filee-kulm-25kg-iqf-ulas-ukraina-halal\/"},"modified":"2026-09-01T19:06:35","modified_gmt":"2026-09-01T16:06:35","slug":"broileri-filee-kulm-25kg-iqf-ulas-ukraina-halal","status":"publish","type":"product","link":"https:\/\/veele.eu\/en\/toode\/broileri-filee-kulm-25kg-iqf-ulas-ukraina-halal\/","title":{"rendered":"BROILERI FILEE  k\u00fclm 2,5KG IQF ULAS (UKRAINA) HALAL"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[211,76],"product_tag":[],"class_list":["post-34864","product","type-product","status-publish","product_cat-kulmutatud-lihatooted","product_cat-liha-tooted","first","instock","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>BROILERI FILEE k\u00fclm 2,5KG IQF ULAS (UKRAINA) HALAL<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/veele.eu\/toode\/broileri-filee-kulm-25kg-iqf-ulas-ukraina-halal\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"BROILERI FILEE k\u00fclm 2,5KG IQF ULAS (UKRAINA) HALAL\" \/>\n<meta property=\"og:url\" content=\"https:\/\/veele.eu\/toode\/broileri-filee-kulm-25kg-iqf-ulas-ukraina-halal\/\" \/>\n<meta property=\"og:site_name\" content=\"VEELE Wholesale food market\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-01T16:06:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/veele.eu\/wp-content\/uploads\/2023\/07\/veele.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"409\" \/>\n\t<meta property=\"og:image:height\" content=\"373\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"6,00&euro;\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/veele.eu\\\/toode\\\/broileri-filee-kulm-25kg-iqf-ulas-ukraina-halal\\\/\",\"url\":\"https:\\\/\\\/veele.eu\\\/toode\\\/broileri-filee-kulm-25kg-iqf-ulas-ukraina-halal\\\/\",\"name\":\"BROILERI FILEE k\u00fclm 2,5KG IQF ULAS (UKRAINA) HALAL\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/veele.eu\\\/#website\"},\"datePublished\":\"2026-09-01T16:06:34+00:00\",\"dateModified\":\"2026-09-01T16:06:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/veele.eu\\\/toode\\\/broileri-filee-kulm-25kg-iqf-ulas-ukraina-halal\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/veele.eu\\\/toode\\\/broileri-filee-kulm-25kg-iqf-ulas-ukraina-halal\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/veele.eu\\\/toode\\\/broileri-filee-kulm-25kg-iqf-ulas-ukraina-halal\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/veele.eu\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Products\",\"item\":\"https:\\\/\\\/veele.eu\\\/en\\\/products\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"BROILERI FILEE k\u00fclm 2,5KG IQF ULAS (UKRAINA) HALAL\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/veele.eu\\\/#website\",\"url\":\"https:\\\/\\\/veele.eu\\\/\",\"name\":\"VEELE Toidukaupade Hulgim\u00fc\u00fck\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/veele.eu\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/veele.eu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/veele.eu\\\/#organization\",\"name\":\"Veele O\u00dc\",\"url\":\"https:\\\/\\\/veele.eu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/veele.eu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/veele.eu\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/veele.jpg\",\"contentUrl\":\"https:\\\/\\\/veele.eu\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/veele.jpg\",\"width\":409,\"height\":373,\"caption\":\"Veele O\u00dc\"},\"image\":{\"@id\":\"https:\\\/\\\/veele.eu\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"6.00\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"BROILERI FILEE k\u00fclm 2,5KG IQF ULAS (UKRAINA) HALAL","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/veele.eu\/toode\/broileri-filee-kulm-25kg-iqf-ulas-ukraina-halal\/","og_locale":"en_US","og_type":"article","og_title":"BROILERI FILEE k\u00fclm 2,5KG IQF ULAS (UKRAINA) HALAL","og_url":"https:\/\/veele.eu\/toode\/broileri-filee-kulm-25kg-iqf-ulas-ukraina-halal\/","og_site_name":"VEELE Wholesale food market","article_modified_time":"2026-09-01T16:06:35+00:00","og_image":[{"width":409,"height":373,"url":"https:\/\/veele.eu\/wp-content\/uploads\/2023\/07\/veele.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"6,00&euro;","Availability":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/veele.eu\/toode\/broileri-filee-kulm-25kg-iqf-ulas-ukraina-halal\/","url":"https:\/\/veele.eu\/toode\/broileri-filee-kulm-25kg-iqf-ulas-ukraina-halal\/","name":"BROILERI FILEE k\u00fclm 2,5KG IQF ULAS (UKRAINA) HALAL","isPartOf":{"@id":"https:\/\/veele.eu\/#website"},"datePublished":"2026-09-01T16:06:34+00:00","dateModified":"2026-09-01T16:06:35+00:00","breadcrumb":{"@id":"https:\/\/veele.eu\/toode\/broileri-filee-kulm-25kg-iqf-ulas-ukraina-halal\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/veele.eu\/toode\/broileri-filee-kulm-25kg-iqf-ulas-ukraina-halal\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/veele.eu\/toode\/broileri-filee-kulm-25kg-iqf-ulas-ukraina-halal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/veele.eu\/en\/"},{"@type":"ListItem","position":2,"name":"Products","item":"https:\/\/veele.eu\/en\/products\/"},{"@type":"ListItem","position":3,"name":"BROILERI FILEE k\u00fclm 2,5KG IQF ULAS (UKRAINA) HALAL"}]},{"@type":"WebSite","@id":"https:\/\/veele.eu\/#website","url":"https:\/\/veele.eu\/","name":"VEELE Toidukaupade Hulgim\u00fc\u00fck","description":"","publisher":{"@id":"https:\/\/veele.eu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/veele.eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/veele.eu\/#organization","name":"Veele O\u00dc","url":"https:\/\/veele.eu\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/veele.eu\/#\/schema\/logo\/image\/","url":"https:\/\/veele.eu\/wp-content\/uploads\/2023\/07\/veele.jpg","contentUrl":"https:\/\/veele.eu\/wp-content\/uploads\/2023\/07\/veele.jpg","width":409,"height":373,"caption":"Veele O\u00dc"},"image":{"@id":"https:\/\/veele.eu\/#\/schema\/logo\/image\/"}}]},"product_price_amount":"6.00","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/veele.eu\/en\/wp-json\/wp\/v2\/product\/34864","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/veele.eu\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/veele.eu\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:attachment":[{"href":"https:\/\/veele.eu\/en\/wp-json\/wp\/v2\/media?parent=34864"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/veele.eu\/en\/wp-json\/wp\/v2\/product_brand?post=34864"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/veele.eu\/en\/wp-json\/wp\/v2\/product_cat?post=34864"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/veele.eu\/en\/wp-json\/wp\/v2\/product_tag?post=34864"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}