{"id":36323,"date":"2026-09-01T19:15:48","date_gmt":"2026-09-01T16:15:48","guid":{"rendered":"https:\/\/veele.eu\/toode\/woro-mm-saslokk-broileri-kintsuliha-ploomi-800gr\/"},"modified":"2026-09-01T19:15:48","modified_gmt":"2026-09-01T16:15:48","slug":"woro-mm-saslokk-broileri-kintsuliha-ploomi-800gr","status":"publish","type":"product","link":"https:\/\/veele.eu\/en\/toode\/woro-mm-saslokk-broileri-kintsuliha-ploomi-800gr\/","title":{"rendered":"W\u00d5RO MM SASL\u00d5KK BROILERI.KINTSULIHA PLOOMI 800GR"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":36344,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[217,76],"product_tag":[],"class_list":["post-36323","product","type-product","status-publish","has-post-thumbnail","product_cat-grilltooted","product_cat-liha-tooted","first","instock","shipping-taxable","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>W\u00d5RO MM SASL\u00d5KK BROILERI.KINTSULIHA PLOOMI 800GR<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/veele.eu\/toode\/woro-mm-saslokk-broileri-kintsuliha-ploomi-800gr\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"W\u00d5RO MM SASL\u00d5KK BROILERI.KINTSULIHA PLOOMI 800GR\" \/>\n<meta property=\"og:url\" content=\"https:\/\/veele.eu\/toode\/woro-mm-saslokk-broileri-kintsuliha-ploomi-800gr\/\" \/>\n<meta property=\"og:site_name\" content=\"VEELE Wholesale food market\" \/>\n<meta property=\"og:image\" content=\"https:\/\/veele.eu\/wp-content\/uploads\/2026\/03\/9999.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"720\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Price\" \/>\n\t<meta name=\"twitter:data1\" content=\"6,70&euro;\" \/>\n\t<meta name=\"twitter:label2\" content=\"Availability\" \/>\n\t<meta name=\"twitter:data2\" content=\"In stock\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/veele.eu\\\/toode\\\/woro-mm-saslokk-broileri-kintsuliha-ploomi-800gr\\\/\",\"url\":\"https:\\\/\\\/veele.eu\\\/toode\\\/woro-mm-saslokk-broileri-kintsuliha-ploomi-800gr\\\/\",\"name\":\"W\u00d5RO MM SASL\u00d5KK BROILERI.KINTSULIHA PLOOMI 800GR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/veele.eu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/veele.eu\\\/toode\\\/woro-mm-saslokk-broileri-kintsuliha-ploomi-800gr\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/veele.eu\\\/toode\\\/woro-mm-saslokk-broileri-kintsuliha-ploomi-800gr\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/veele.eu\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/9999.webp\",\"datePublished\":\"2026-09-01T16:15:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/veele.eu\\\/toode\\\/woro-mm-saslokk-broileri-kintsuliha-ploomi-800gr\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/veele.eu\\\/toode\\\/woro-mm-saslokk-broileri-kintsuliha-ploomi-800gr\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/veele.eu\\\/toode\\\/woro-mm-saslokk-broileri-kintsuliha-ploomi-800gr\\\/#primaryimage\",\"url\":\"https:\\\/\\\/veele.eu\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/9999.webp\",\"contentUrl\":\"https:\\\/\\\/veele.eu\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/9999.webp\",\"width\":720,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/veele.eu\\\/toode\\\/woro-mm-saslokk-broileri-kintsuliha-ploomi-800gr\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/veele.eu\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Products\",\"item\":\"https:\\\/\\\/veele.eu\\\/en\\\/products\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"W\u00d5RO MM SASL\u00d5KK BROILERI.KINTSULIHA PLOOMI 800GR\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/veele.eu\\\/#website\",\"url\":\"https:\\\/\\\/veele.eu\\\/\",\"name\":\"VEELE Toidukaupade Hulgim\u00fc\u00fck\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/veele.eu\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/veele.eu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/veele.eu\\\/#organization\",\"name\":\"Veele O\u00dc\",\"url\":\"https:\\\/\\\/veele.eu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/veele.eu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/veele.eu\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/veele.jpg\",\"contentUrl\":\"https:\\\/\\\/veele.eu\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/veele.jpg\",\"width\":409,\"height\":373,\"caption\":\"Veele O\u00dc\"},\"image\":{\"@id\":\"https:\\\/\\\/veele.eu\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<meta property=\"product:price:amount\" content=\"6.70\" \/>\n<meta property=\"product:price:currency\" content=\"EUR\" \/>\n<meta property=\"og:availability\" content=\"instock\" \/>\n<meta property=\"product:availability\" content=\"instock\" \/>\n<meta property=\"product:retailer_item_id\" content=\"4740171183657\" \/>\n<meta property=\"product:condition\" content=\"new\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"W\u00d5RO MM SASL\u00d5KK BROILERI.KINTSULIHA PLOOMI 800GR","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/veele.eu\/toode\/woro-mm-saslokk-broileri-kintsuliha-ploomi-800gr\/","og_locale":"en_US","og_type":"article","og_title":"W\u00d5RO MM SASL\u00d5KK BROILERI.KINTSULIHA PLOOMI 800GR","og_url":"https:\/\/veele.eu\/toode\/woro-mm-saslokk-broileri-kintsuliha-ploomi-800gr\/","og_site_name":"VEELE Wholesale food market","og_image":[{"width":720,"height":720,"url":"https:\/\/veele.eu\/wp-content\/uploads\/2026\/03\/9999.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Price":"6,70&euro;","Availability":"In stock"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/veele.eu\/toode\/woro-mm-saslokk-broileri-kintsuliha-ploomi-800gr\/","url":"https:\/\/veele.eu\/toode\/woro-mm-saslokk-broileri-kintsuliha-ploomi-800gr\/","name":"W\u00d5RO MM SASL\u00d5KK BROILERI.KINTSULIHA PLOOMI 800GR","isPartOf":{"@id":"https:\/\/veele.eu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/veele.eu\/toode\/woro-mm-saslokk-broileri-kintsuliha-ploomi-800gr\/#primaryimage"},"image":{"@id":"https:\/\/veele.eu\/toode\/woro-mm-saslokk-broileri-kintsuliha-ploomi-800gr\/#primaryimage"},"thumbnailUrl":"https:\/\/veele.eu\/wp-content\/uploads\/2026\/03\/9999.webp","datePublished":"2026-09-01T16:15:48+00:00","breadcrumb":{"@id":"https:\/\/veele.eu\/toode\/woro-mm-saslokk-broileri-kintsuliha-ploomi-800gr\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/veele.eu\/toode\/woro-mm-saslokk-broileri-kintsuliha-ploomi-800gr\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/veele.eu\/toode\/woro-mm-saslokk-broileri-kintsuliha-ploomi-800gr\/#primaryimage","url":"https:\/\/veele.eu\/wp-content\/uploads\/2026\/03\/9999.webp","contentUrl":"https:\/\/veele.eu\/wp-content\/uploads\/2026\/03\/9999.webp","width":720,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/veele.eu\/toode\/woro-mm-saslokk-broileri-kintsuliha-ploomi-800gr\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/veele.eu\/en\/"},{"@type":"ListItem","position":2,"name":"Products","item":"https:\/\/veele.eu\/en\/products\/"},{"@type":"ListItem","position":3,"name":"W\u00d5RO MM SASL\u00d5KK BROILERI.KINTSULIHA PLOOMI 800GR"}]},{"@type":"WebSite","@id":"https:\/\/veele.eu\/#website","url":"https:\/\/veele.eu\/","name":"VEELE Toidukaupade Hulgim\u00fc\u00fck","description":"","publisher":{"@id":"https:\/\/veele.eu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/veele.eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/veele.eu\/#organization","name":"Veele O\u00dc","url":"https:\/\/veele.eu\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/veele.eu\/#\/schema\/logo\/image\/","url":"https:\/\/veele.eu\/wp-content\/uploads\/2023\/07\/veele.jpg","contentUrl":"https:\/\/veele.eu\/wp-content\/uploads\/2023\/07\/veele.jpg","width":409,"height":373,"caption":"Veele O\u00dc"},"image":{"@id":"https:\/\/veele.eu\/#\/schema\/logo\/image\/"}}]},"product_price_amount":"6.70","product_price_currency":"EUR","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"4740171183657","product_condition":"new"},"_links":{"self":[{"href":"https:\/\/veele.eu\/en\/wp-json\/wp\/v2\/product\/36323","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/veele.eu\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/veele.eu\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/veele.eu\/en\/wp-json\/wp\/v2\/media\/36344"}],"wp:attachment":[{"href":"https:\/\/veele.eu\/en\/wp-json\/wp\/v2\/media?parent=36323"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/veele.eu\/en\/wp-json\/wp\/v2\/product_brand?post=36323"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/veele.eu\/en\/wp-json\/wp\/v2\/product_cat?post=36323"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/veele.eu\/en\/wp-json\/wp\/v2\/product_tag?post=36323"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}